{"id":99419,"date":"2023-12-04T19:00:00","date_gmt":"2023-12-04T19:00:00","guid":{"rendered":"https:\/\/www.altominho.tv\/site\/?p=99419"},"modified":"2023-12-04T16:40:37","modified_gmt":"2023-12-04T16:40:37","slug":"campo-em-festa-esta-de-volta-daqui-a-2-meses","status":"publish","type":"post","link":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/","title":{"rendered":"Campo em Festa est\u00e1 de volta daqui a 2 meses"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Campo em Festa est\u00e1 de volta daqui a 2 meses | Altominho TV\" width=\"770\" height=\"433\" src=\"https:\/\/www.youtube.com\/embed\/M1JcZzC735c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n<p>A uni\u00e3o de freguesias de Anh\u00f5es e Luzio j\u00e1 est\u00e1 a preparar a pr\u00f3xima edi\u00e7\u00e3o do Campo em Festa. A dois meses do evento, a Altominho TV esteve \u00e0 conversa com o presidente da junta de freguesia para saber o que \u00e9 esta festa e como correm os preparativos.<\/p>\n<p>O Campo em Festa est\u00e1 agendado para os dias 3 e 4 de fevereiro e promove o conv\u00edvio e a uni\u00e3o de toda a comunidade, respons\u00e1vel pela produ\u00e7\u00e3o e cultivo dos produtos oferecidos na festa.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>A uni\u00e3o de freguesias de Anh\u00f5es e Luzio j\u00e1 est\u00e1 a preparar a pr\u00f3xima edi\u00e7\u00e3o do Campo em Festa. A dois meses do evento, a Altominho TV esteve \u00e0 conversa com o presidente da junta de freguesia para saber o que \u00e9 esta festa e como correm os preparativos. O Campo em Festa est\u00e1 agendado [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":99421,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[9],"tags":[81,27],"class_list":["post-99419","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-moncao","tag-gastronomia","tag-sociedade","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Campo em Festa est\u00e1 de volta daqui a 2 meses<\/title>\n<meta name=\"description\" content=\"O Campo em Festa est\u00e1 agendado para os dias 3 e 4 de fevereiro e promove o conv\u00edvio e a uni\u00e3o de toda a comunidade.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campo em Festa est\u00e1 de volta daqui a 2 meses\" \/>\n<meta property=\"og:description\" content=\"O Campo em Festa est\u00e1 agendado para os dias 3 e 4 de fevereiro e promove o conv\u00edvio e a uni\u00e3o de toda a comunidade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/\" \/>\n<meta property=\"og:site_name\" content=\"Altominho.tv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/altominhotv\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-04T19:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/12\/Cozido-Anhoes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexandre Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:site\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexandre Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/\"},\"author\":{\"name\":\"Alexandre Ferreira\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/56c462a0f6591602f4e9fb3fa6ea49bd\"},\"headline\":\"Campo em Festa est\u00e1 de volta daqui a 2 meses\",\"datePublished\":\"2023-12-04T19:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/\"},\"wordCount\":103,\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Cozido-Anhoes.jpg\",\"keywords\":[\"Gastronomia\",\"Sociedade\"],\"articleSection\":[\"Mon\u00e7\u00e3o\"],\"inLanguage\":\"pt-PT\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/\",\"name\":\"Campo em Festa est\u00e1 de volta daqui a 2 meses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Cozido-Anhoes.jpg\",\"datePublished\":\"2023-12-04T19:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/56c462a0f6591602f4e9fb3fa6ea49bd\"},\"description\":\"O Campo em Festa est\u00e1 agendado para os dias 3 e 4 de fevereiro e promove o conv\u00edvio e a uni\u00e3o de toda a comunidade.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Cozido-Anhoes.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Cozido-Anhoes.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/12\\\/04\\\/campo-em-festa-esta-de-volta-daqui-a-2-meses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campo em Festa est\u00e1 de volta daqui a 2 meses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\",\"name\":\"Altominho.tv\",\"description\":\"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/56c462a0f6591602f4e9fb3fa6ea49bd\",\"name\":\"Alexandre Ferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Alexandre-150x150.jpg\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Alexandre-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Alexandre-150x150.jpg\",\"caption\":\"Alexandre Ferreira\"},\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/author\\\/alexandreferreira\\\/\"}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/M1JcZzC735c\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"90\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:upload_date\" content=\"2023-12-04T19:00:00+00:00\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Campo em Festa est\u00e1 de volta daqui a 2 meses","description":"O Campo em Festa est\u00e1 agendado para os dias 3 e 4 de fevereiro e promove o conv\u00edvio e a uni\u00e3o de toda a comunidade.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/","og_locale":"pt_PT","og_type":"article","og_title":"Campo em Festa est\u00e1 de volta daqui a 2 meses","og_description":"O Campo em Festa est\u00e1 agendado para os dias 3 e 4 de fevereiro e promove o conv\u00edvio e a uni\u00e3o de toda a comunidade.","og_url":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/","og_site_name":"Altominho.tv","article_publisher":"https:\/\/www.facebook.com\/altominhotv","article_published_time":"2023-12-04T19:00:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/12\/Cozido-Anhoes.jpg","type":"image\/jpeg"}],"author":"Alexandre Ferreira","twitter_card":"summary_large_image","twitter_creator":"@altominhoTV","twitter_site":"@altominhoTV","twitter_misc":{"Escrito por":"Alexandre Ferreira","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/#article","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/"},"author":{"name":"Alexandre Ferreira","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/56c462a0f6591602f4e9fb3fa6ea49bd"},"headline":"Campo em Festa est\u00e1 de volta daqui a 2 meses","datePublished":"2023-12-04T19:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/"},"wordCount":103,"image":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/12\/Cozido-Anhoes.jpg","keywords":["Gastronomia","Sociedade"],"articleSection":["Mon\u00e7\u00e3o"],"inLanguage":"pt-PT","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.altominho.tv\/site\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/","url":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/","name":"Campo em Festa est\u00e1 de volta daqui a 2 meses","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/#primaryimage"},"image":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/12\/Cozido-Anhoes.jpg","datePublished":"2023-12-04T19:00:00+00:00","author":{"@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/56c462a0f6591602f4e9fb3fa6ea49bd"},"description":"O Campo em Festa est\u00e1 agendado para os dias 3 e 4 de fevereiro e promove o conv\u00edvio e a uni\u00e3o de toda a comunidade.","breadcrumb":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/#primaryimage","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/12\/Cozido-Anhoes.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/12\/Cozido-Anhoes.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.altominho.tv\/site\/2023\/12\/04\/campo-em-festa-esta-de-volta-daqui-a-2-meses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.altominho.tv\/site\/"},{"@type":"ListItem","position":2,"name":"Campo em Festa est\u00e1 de volta daqui a 2 meses"}]},{"@type":"WebSite","@id":"https:\/\/www.altominho.tv\/site\/#website","url":"https:\/\/www.altominho.tv\/site\/","name":"Altominho.tv","description":"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.altominho.tv\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/56c462a0f6591602f4e9fb3fa6ea49bd","name":"Alexandre Ferreira","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2017\/11\/Alexandre-150x150.jpg","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2017\/11\/Alexandre-150x150.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2017\/11\/Alexandre-150x150.jpg","caption":"Alexandre Ferreira"},"url":"https:\/\/www.altominho.tv\/site\/author\/alexandreferreira\/"}]},"og_video":"https:\/\/www.youtube.com\/embed\/M1JcZzC735c","og_video_type":"text\/html","og_video_duration":"90","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_upload_date":"2023-12-04T19:00:00+00:00","ya_ovs_allow_embed":"true"},"_links":{"self":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/99419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/comments?post=99419"}],"version-history":[{"count":1,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/99419\/revisions"}],"predecessor-version":[{"id":99420,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/99419\/revisions\/99420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media\/99421"}],"wp:attachment":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media?parent=99419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/categories?post=99419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/tags?post=99419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}