{"id":96468,"date":"2023-09-14T09:12:23","date_gmt":"2023-09-14T08:12:23","guid":{"rendered":"https:\/\/www.altominho.tv\/site\/?p=96468"},"modified":"2023-09-14T09:14:59","modified_gmt":"2023-09-14T08:14:59","slug":"bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias","status":"publish","type":"post","link":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/","title":{"rendered":"Bombeiros receberam de presente uma ambul\u00e2ncia de socorro ABSC do &#8216;Natal a Meias&#8217;"},"content":{"rendered":"<p>A Associa\u00e7\u00e3o Humanit\u00e1ria dos Bombeiros Volunt\u00e1rios de Arcos de Valdevez (AHBVAV) recebeu, atrav\u00e9s do projeto &#8216;Natal a Meias&#8217;, realizado pela TVI e pela Calzedonia, &#8220;um presente de Natal que salva vidas&#8221;: uma ambul\u00e2ncia de socorro ABSC, anunciaram os bombeiros na rede social Facebook.<\/p>\n<p>O presidente Germano Amorim e o comandante Filipe Guimar\u00e3es da AHBVAV, marcaram presen\u00e7a na cerim\u00f3nia de entrega da nova ambul\u00e2ncia na sede da Liga dos Bombeiros Portuguese (LBP), em Lisboa.<\/p>\n<p>Na publica\u00e7\u00e3o feita nas redes sociais, os Bombeiros Volunt\u00e1rios de Arcos de Valdevez expressaram um &#8220;enorme sentimento de gratid\u00e3o&#8221; \u00e0 TVI e \u00e0 Calzedonia que, atrav\u00e9s da iniciativa &#8216;Natal a Meias&#8217;, &#8220;trouxeram este presente antecipado&#8221;.<\/p>\n<p>&#8220;A AHBVAV agradece com profunda gratid\u00e3o. A ambul\u00e2ncia ABSC oferecida \u00e9 uma d\u00e1diva inestim\u00e1vel para as nossas opera\u00e7\u00f5es e a nossa capacidade de servir a comunidade. Juntos continuaremos a fazer a diferen\u00e7a na vidas das pessoas&#8221;, conclu\u00edram os bombeiros na publica\u00e7\u00e3o realizada no Facebook.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Associa\u00e7\u00e3o Humanit\u00e1ria dos Bombeiros Volunt\u00e1rios de Arcos de Valdevez (AHBVAV) recebeu, atrav\u00e9s do projeto &#8216;Natal a Meias&#8217;, realizado pela TVI e pela Calzedonia, &#8220;um presente de Natal que salva vidas&#8221;: uma ambul\u00e2ncia de socorro ABSC, anunciaram os bombeiros na rede social Facebook. O presidente Germano Amorim e o comandante Filipe Guimar\u00e3es da AHBVAV, marcaram [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":96469,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[2],"tags":[26,27],"class_list":["post-96468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arcos-de-valdevez","tag-saude","tag-sociedade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bombeiros receberam de presente uma ambul\u00e2ncia de socorro ABSC do &#039;Natal a Meias&#039;<\/title>\n<meta name=\"description\" content=\"A Associa\u00e7\u00e3o Humanit\u00e1ria dos Bombeiros Volunt\u00e1rios de Arcos de Valdevez (AHBVAV) recebeu, atrav\u00e9s do projeto &#039;Natal a Meias&#039;, realizado pela TVI e pela Calzedonia, &quot;um presente de Natal que salva vidas&quot;: uma ambul\u00e2ncia de socorro ABSC, anunciaram os bombeiros na rede social Facebook.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bombeiros receberam de presente uma ambul\u00e2ncia de socorro ABSC do &#039;Natal a Meias&#039;\" \/>\n<meta property=\"og:description\" content=\"A Associa\u00e7\u00e3o Humanit\u00e1ria dos Bombeiros Volunt\u00e1rios de Arcos de Valdevez (AHBVAV) recebeu, atrav\u00e9s do projeto &#039;Natal a Meias&#039;, realizado pela TVI e pela Calzedonia, &quot;um presente de Natal que salva vidas&quot;: uma ambul\u00e2ncia de socorro ABSC, anunciaram os bombeiros na rede social Facebook.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/\" \/>\n<meta property=\"og:site_name\" content=\"Altominho.tv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/altominhotv\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-14T08:12:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-14T08:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/09\/Bombeiros-Arcos-de-Valdevez.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1065\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Altominho.tv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:site\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Altominho.tv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/\"},\"author\":{\"name\":\"Altominho.tv\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\"},\"headline\":\"Bombeiros receberam de presente uma ambul\u00e2ncia de socorro ABSC do &#8216;Natal a Meias&#8217;\",\"datePublished\":\"2023-09-14T08:12:23+00:00\",\"dateModified\":\"2023-09-14T08:14:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/\"},\"wordCount\":184,\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Bombeiros-Arcos-de-Valdevez.jpg\",\"keywords\":[\"Sa\u00fade\",\"Sociedade\"],\"articleSection\":[\"Arcos de Valdevez\"],\"inLanguage\":\"pt-PT\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/\",\"name\":\"Bombeiros receberam de presente uma ambul\u00e2ncia de socorro ABSC do 'Natal a Meias'\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Bombeiros-Arcos-de-Valdevez.jpg\",\"datePublished\":\"2023-09-14T08:12:23+00:00\",\"dateModified\":\"2023-09-14T08:14:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\"},\"description\":\"A Associa\u00e7\u00e3o Humanit\u00e1ria dos Bombeiros Volunt\u00e1rios de Arcos de Valdevez (AHBVAV) recebeu, atrav\u00e9s do projeto 'Natal a Meias', realizado pela TVI e pela Calzedonia, \\\"um presente de Natal que salva vidas\\\": uma ambul\u00e2ncia de socorro ABSC, anunciaram os bombeiros na rede social Facebook.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Bombeiros-Arcos-de-Valdevez.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Bombeiros-Arcos-de-Valdevez.jpg\",\"width\":1065,\"height\":710},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/09\\\/14\\\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bombeiros receberam de presente uma ambul\u00e2ncia de socorro ABSC do &#8216;Natal a Meias&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\",\"name\":\"Altominho.tv\",\"description\":\"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\",\"name\":\"Altominho.tv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"caption\":\"Altominho.tv\"},\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/author\\\/altominhotv-tecnico\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bombeiros receberam de presente uma ambul\u00e2ncia de socorro ABSC do 'Natal a Meias'","description":"A Associa\u00e7\u00e3o Humanit\u00e1ria dos Bombeiros Volunt\u00e1rios de Arcos de Valdevez (AHBVAV) recebeu, atrav\u00e9s do projeto 'Natal a Meias', realizado pela TVI e pela Calzedonia, \"um presente de Natal que salva vidas\": uma ambul\u00e2ncia de socorro ABSC, anunciaram os bombeiros na rede social Facebook.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/","og_locale":"pt_PT","og_type":"article","og_title":"Bombeiros receberam de presente uma ambul\u00e2ncia de socorro ABSC do 'Natal a Meias'","og_description":"A Associa\u00e7\u00e3o Humanit\u00e1ria dos Bombeiros Volunt\u00e1rios de Arcos de Valdevez (AHBVAV) recebeu, atrav\u00e9s do projeto 'Natal a Meias', realizado pela TVI e pela Calzedonia, \"um presente de Natal que salva vidas\": uma ambul\u00e2ncia de socorro ABSC, anunciaram os bombeiros na rede social Facebook.","og_url":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/","og_site_name":"Altominho.tv","article_publisher":"https:\/\/www.facebook.com\/altominhotv","article_published_time":"2023-09-14T08:12:23+00:00","article_modified_time":"2023-09-14T08:14:59+00:00","og_image":[{"width":1065,"height":710,"url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/09\/Bombeiros-Arcos-de-Valdevez.jpg","type":"image\/jpeg"}],"author":"Altominho.tv","twitter_card":"summary_large_image","twitter_creator":"@altominhoTV","twitter_site":"@altominhoTV","twitter_misc":{"Escrito por":"Altominho.tv","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/#article","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/"},"author":{"name":"Altominho.tv","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22"},"headline":"Bombeiros receberam de presente uma ambul\u00e2ncia de socorro ABSC do &#8216;Natal a Meias&#8217;","datePublished":"2023-09-14T08:12:23+00:00","dateModified":"2023-09-14T08:14:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/"},"wordCount":184,"image":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/09\/Bombeiros-Arcos-de-Valdevez.jpg","keywords":["Sa\u00fade","Sociedade"],"articleSection":["Arcos de Valdevez"],"inLanguage":"pt-PT","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.altominho.tv\/site\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/","url":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/","name":"Bombeiros receberam de presente uma ambul\u00e2ncia de socorro ABSC do 'Natal a Meias'","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/#primaryimage"},"image":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/09\/Bombeiros-Arcos-de-Valdevez.jpg","datePublished":"2023-09-14T08:12:23+00:00","dateModified":"2023-09-14T08:14:59+00:00","author":{"@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22"},"description":"A Associa\u00e7\u00e3o Humanit\u00e1ria dos Bombeiros Volunt\u00e1rios de Arcos de Valdevez (AHBVAV) recebeu, atrav\u00e9s do projeto 'Natal a Meias', realizado pela TVI e pela Calzedonia, \"um presente de Natal que salva vidas\": uma ambul\u00e2ncia de socorro ABSC, anunciaram os bombeiros na rede social Facebook.","breadcrumb":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/#primaryimage","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/09\/Bombeiros-Arcos-de-Valdevez.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/09\/Bombeiros-Arcos-de-Valdevez.jpg","width":1065,"height":710},{"@type":"BreadcrumbList","@id":"https:\/\/www.altominho.tv\/site\/2023\/09\/14\/bombeiros-receberam-de-presente-uma-ambulancia-de-socorro-absc-do-natal-a-meias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.altominho.tv\/site\/"},{"@type":"ListItem","position":2,"name":"Bombeiros receberam de presente uma ambul\u00e2ncia de socorro ABSC do &#8216;Natal a Meias&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/www.altominho.tv\/site\/#website","url":"https:\/\/www.altominho.tv\/site\/","name":"Altominho.tv","description":"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.altominho.tv\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22","name":"Altominho.tv","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","caption":"Altominho.tv"},"url":"https:\/\/www.altominho.tv\/site\/author\/altominhotv-tecnico\/"}]}},"_links":{"self":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/96468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/comments?post=96468"}],"version-history":[{"count":2,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/96468\/revisions"}],"predecessor-version":[{"id":96471,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/96468\/revisions\/96471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media\/96469"}],"wp:attachment":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media?parent=96468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/categories?post=96468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/tags?post=96468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}