{"id":93624,"date":"2023-06-21T17:28:07","date_gmt":"2023-06-21T16:28:07","guid":{"rendered":"https:\/\/www.altominho.tv\/site\/?p=93624"},"modified":"2023-06-21T17:28:12","modified_gmt":"2023-06-21T16:28:12","slug":"camara-quer-atrair-mais-visitantes-centro-historico-caminha","status":"publish","type":"post","link":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/","title":{"rendered":"C\u00e2mara quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha"},"content":{"rendered":"<p>A C\u00e2mara Municipal quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha e dinamizar o com\u00e9rcio local, facilitando a frui\u00e7\u00e3o de algumas das principais art\u00e9rias que, \u00e0 semelhan\u00e7a de anos anteriores, ser\u00e3o vedadas ao tr\u00e2nsito autom\u00f3vel ao s\u00e1bado e ao domingo.<\/p>\n<p>A decis\u00e3o foi concertada com a Uni\u00e3o de Freguesias de Caminha e Vilarelho, tendo em conta a experi\u00eancia anterior, e aprovada hoje, em reuni\u00e3o do Executivo.<\/p>\n<p>Conclu\u00eddas as obras de reabilita\u00e7\u00e3o do Centro Hist\u00f3rico de Caminha, em 2021, as quest\u00f5es do tr\u00e2nsito autom\u00f3vel e do estacionamento foram debatidas com a popula\u00e7\u00e3o, comerciantes e \u00f3rg\u00e3os locais, tendo-se chegado a uma solu\u00e7\u00e3o consensual.<\/p>\n<p>Nesse ver\u00e3o, tamb\u00e9m, implementaram-se regras distintas aos fins de semana, libertando o espa\u00e7o p\u00fablico para as pessoas e para as fam\u00edlias e facilitando o acesso \u00e0s lojas e demais estabelecimento.<\/p>\n<p>O balan\u00e7o foi claramente positivo e, ponderada a situa\u00e7\u00e3o, aprovou-se hoje a altera\u00e7\u00e3o tempor\u00e1ria da postura de tr\u00e2nsito e estacionamento, na Uni\u00e3o de Freguesias de Caminha e Vilarelho, nas seguintes condi\u00e7\u00f5es:<\/p>\n<ul>\n<li>Altera\u00e7\u00e3o tempor\u00e1ria da postura de tr\u00e2nsito para tr\u00e2nsito proibido exceto ve\u00edculos autorizados, servi\u00e7os afetos \u00e0 recolha de res\u00edduos s\u00f3lidos urbanos, viaturas municipais, viaturas de emerg\u00eancia e t\u00e1xis, na Rua de S\u00e3o Jo\u00e3o e Pra\u00e7a Conselheiro Silva Torres, entre a entrada para o parque de estacionamento do tribunal e a Rua Visconde de Sousa Rego, aos fins de semana, nomeadamente ao s\u00e1bado e ao domingo, entre as 22h00 de sexta-feira e as 22h00 de domingo, entre o dia 23 de junho e o dia 3 de setembro do corrente ano;<\/li>\n<li>Altera\u00e7\u00e3o tempor\u00e1ria da postura de tr\u00e2nsito para tr\u00e2nsito proibido exceto Bombeiros, RSU e T\u00e1xis, na Rua Comandante Lino Felgueiras da Silva, aos fins de semana, nomeadamente ao s\u00e1bado e ao domingo, entre as 22h00 de sexta-feira e as 22h00 de domingo, entre o dia 23 de junho e o dia 3 de setembro do corrente ano;<\/li>\n<li>Altera\u00e7\u00e3o tempor\u00e1ria ao estacionamento autom\u00f3vel para estacionamento proibido na Rua de S\u00e3o Jo\u00e3o e Pra\u00e7a Conselheiro Silva Torres, entre a entrada para o parque de estacionamento do tribunal e a Rua Visconde de Sousa Rego, aos fins de semana, nomeadamente ao s\u00e1bado e ao domingo, entre as 22h00 de sexta-feira e as 22h00 de domingo, entre o dia 23 de junho e o dia 3 de setembro do corrente ano.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara Municipal quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha e dinamizar o com\u00e9rcio local, facilitando a frui\u00e7\u00e3o de algumas das principais art\u00e9rias que, \u00e0 semelhan\u00e7a de anos anteriores, ser\u00e3o vedadas ao tr\u00e2nsito autom\u00f3vel ao s\u00e1bado e ao domingo. A decis\u00e3o foi concertada com a Uni\u00e3o de Freguesias de Caminha e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":93625,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[56326],"class_list":["post-93624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caminha","tag-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>C\u00e2mara quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha<\/title>\n<meta name=\"description\" content=\"A C\u00e2mara Municipal quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha e dinamizar o com\u00e9rcio local, facilitando a frui\u00e7\u00e3o de algumas das principais art\u00e9rias que, \u00e0 semelhan\u00e7a de anos anteriores, ser\u00e3o vedadas ao tr\u00e2nsito autom\u00f3vel ao s\u00e1bado e ao domingo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e2mara quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha\" \/>\n<meta property=\"og:description\" content=\"A C\u00e2mara Municipal quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha e dinamizar o com\u00e9rcio local, facilitando a frui\u00e7\u00e3o de algumas das principais art\u00e9rias que, \u00e0 semelhan\u00e7a de anos anteriores, ser\u00e3o vedadas ao tr\u00e2nsito autom\u00f3vel ao s\u00e1bado e ao domingo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/\" \/>\n<meta property=\"og:site_name\" content=\"Altominho.tv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/altominhotv\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-21T16:28:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-21T16:28:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/06\/Caminha.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Altominho.tv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:site\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Altominho.tv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/\"},\"author\":{\"name\":\"Altominho.tv\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\"},\"headline\":\"C\u00e2mara quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha\",\"datePublished\":\"2023-06-21T16:28:07+00:00\",\"dateModified\":\"2023-06-21T16:28:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/\"},\"wordCount\":447,\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Caminha-e1708688144663.jpg\",\"keywords\":[\"Pol\u00edtica\"],\"articleSection\":[\"Caminha\"],\"inLanguage\":\"pt-PT\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/\",\"name\":\"C\u00e2mara quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Caminha-e1708688144663.jpg\",\"datePublished\":\"2023-06-21T16:28:07+00:00\",\"dateModified\":\"2023-06-21T16:28:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\"},\"description\":\"A C\u00e2mara Municipal quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha e dinamizar o com\u00e9rcio local, facilitando a frui\u00e7\u00e3o de algumas das principais art\u00e9rias que, \u00e0 semelhan\u00e7a de anos anteriores, ser\u00e3o vedadas ao tr\u00e2nsito autom\u00f3vel ao s\u00e1bado e ao domingo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Caminha-e1708688144663.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Caminha-e1708688144663.jpg\",\"width\":1620,\"height\":912},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2023\\\/06\\\/21\\\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e2mara quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\",\"name\":\"Altominho.tv\",\"description\":\"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\",\"name\":\"Altominho.tv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"caption\":\"Altominho.tv\"},\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/author\\\/altominhotv-tecnico\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"C\u00e2mara quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha","description":"A C\u00e2mara Municipal quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha e dinamizar o com\u00e9rcio local, facilitando a frui\u00e7\u00e3o de algumas das principais art\u00e9rias que, \u00e0 semelhan\u00e7a de anos anteriores, ser\u00e3o vedadas ao tr\u00e2nsito autom\u00f3vel ao s\u00e1bado e ao domingo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/","og_locale":"pt_PT","og_type":"article","og_title":"C\u00e2mara quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha","og_description":"A C\u00e2mara Municipal quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha e dinamizar o com\u00e9rcio local, facilitando a frui\u00e7\u00e3o de algumas das principais art\u00e9rias que, \u00e0 semelhan\u00e7a de anos anteriores, ser\u00e3o vedadas ao tr\u00e2nsito autom\u00f3vel ao s\u00e1bado e ao domingo.","og_url":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/","og_site_name":"Altominho.tv","article_publisher":"https:\/\/www.facebook.com\/altominhotv","article_published_time":"2023-06-21T16:28:07+00:00","article_modified_time":"2023-06-21T16:28:12+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/06\/Caminha.jpg","type":"image\/jpeg"}],"author":"Altominho.tv","twitter_card":"summary_large_image","twitter_creator":"@altominhoTV","twitter_site":"@altominhoTV","twitter_misc":{"Escrito por":"Altominho.tv","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/#article","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/"},"author":{"name":"Altominho.tv","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22"},"headline":"C\u00e2mara quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha","datePublished":"2023-06-21T16:28:07+00:00","dateModified":"2023-06-21T16:28:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/"},"wordCount":447,"image":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/06\/Caminha-e1708688144663.jpg","keywords":["Pol\u00edtica"],"articleSection":["Caminha"],"inLanguage":"pt-PT","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.altominho.tv\/site\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/","url":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/","name":"C\u00e2mara quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/#primaryimage"},"image":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/06\/Caminha-e1708688144663.jpg","datePublished":"2023-06-21T16:28:07+00:00","dateModified":"2023-06-21T16:28:12+00:00","author":{"@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22"},"description":"A C\u00e2mara Municipal quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha e dinamizar o com\u00e9rcio local, facilitando a frui\u00e7\u00e3o de algumas das principais art\u00e9rias que, \u00e0 semelhan\u00e7a de anos anteriores, ser\u00e3o vedadas ao tr\u00e2nsito autom\u00f3vel ao s\u00e1bado e ao domingo.","breadcrumb":{"@id":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/#primaryimage","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/06\/Caminha-e1708688144663.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2023\/06\/Caminha-e1708688144663.jpg","width":1620,"height":912},{"@type":"BreadcrumbList","@id":"https:\/\/www.altominho.tv\/site\/2023\/06\/21\/camara-quer-atrair-mais-visitantes-centro-historico-caminha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.altominho.tv\/site\/"},{"@type":"ListItem","position":2,"name":"C\u00e2mara quer atrair cada vez mais visitantes ao Centro Hist\u00f3rico de Caminha"}]},{"@type":"WebSite","@id":"https:\/\/www.altominho.tv\/site\/#website","url":"https:\/\/www.altominho.tv\/site\/","name":"Altominho.tv","description":"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.altominho.tv\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22","name":"Altominho.tv","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","caption":"Altominho.tv"},"url":"https:\/\/www.altominho.tv\/site\/author\/altominhotv-tecnico\/"}]}},"_links":{"self":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/93624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/comments?post=93624"}],"version-history":[{"count":1,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/93624\/revisions"}],"predecessor-version":[{"id":93626,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/93624\/revisions\/93626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media\/93625"}],"wp:attachment":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media?parent=93624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/categories?post=93624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/tags?post=93624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}