{"id":79654,"date":"2022-05-11T09:52:20","date_gmt":"2022-05-11T08:52:20","guid":{"rendered":"https:\/\/www.altominho.tv\/site\/?p=79654"},"modified":"2022-05-11T09:52:25","modified_gmt":"2022-05-11T08:52:25","slug":"parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios","status":"publish","type":"post","link":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/","title":{"rendered":"Parque Nacional Peneda Ger\u00eas quer mecanismo que agilize acesso a fundos comunit\u00e1rios"},"content":{"rendered":"<p>O presidente da Comiss\u00e3o de Cogest\u00e3o do Parque Nacional da Peneda-Ger\u00eas (PNPG) defendeu a cria\u00e7\u00e3o naquele territ\u00f3rio de uma Interven\u00e7\u00e3o Territorial Integrada (ITI), um mecanismo que permitir\u00e1 agilizar o acesso a fundos comunit\u00e1rios.<\/p>\n<p>Em declara\u00e7\u00f5es \u00e0 ag\u00eancia Lusa, a prop\u00f3sito dos 51 anos do PNPG, assinalados na segunda-feira, numa sess\u00e3o\u00a0na Gavieira, em Arcos de Valdevez, Jo\u00e3o Manuel Esteves, explicou que a cria\u00e7\u00e3o daquela ITI \u201cpermite criar um instrumento espec\u00edfico para financiamento de projetos na \u00e1rea do parque nacional\u201d.<\/p>\n<p>\u201c\u00c9 necess\u00e1rio o reconhecimento efetivo, n\u00e3o pelo nome de parque nacional, mas por ser um territ\u00f3rio de excel\u00eancia a n\u00edvel nacional\u201d, sustentou Jo\u00e3o Manuel Esteves, que \u00e9 tamb\u00e9m presidente da C\u00e2mara de Arcos de Valdevez, no distrito de Viana do Castelo.<\/p>\n<p>O PNPG atravessa 22 freguesias, situa-se no extremo noroeste de Portugal, na zona raiana entre Minho, Tr\u00e1s-os-Montes e a Galiza, atravessando os distritos de Braga (Terras de Bouro), Viana do Castelo (Melga\u00e7o, Arcos de Valdevez e Ponte da Barca) e Vila Real (Montalegre), tendo uma \u00e1rea total de 70.290 hectares.<\/p>\n<p>Al\u00e9m da cria\u00e7\u00e3o da ITI, o autarca social-democrata, e presidente da Comiss\u00e3o de Cogest\u00e3o do PNPG, defendeu o \u201crefor\u00e7o das equipas do Corpo Nacional de Agentes Florestais (CNAF) e de Sapadores Florestais que, \u201cpara al\u00e9m de melhorarem a preven\u00e7\u00e3o de fogos florestais e a prote\u00e7\u00e3o de pessoas e bens, garantir\u00e1 a cria\u00e7\u00e3o de postos de trabalho\u201d.<\/p>\n<p>\u201cAtualmente, o PNPG tem 50 sapadores. Pretend\u00edamos dotar cada um dos cinco concelhos que integram o parque, com mais uma equipa\u201d, especificou.<\/p>\n<p>Jo\u00e3o Manuel Esteves pediu ainda \u201co refor\u00e7o do protocolo com o Fundo Ambiental para a melhoria das condi\u00e7\u00f5es de visita\u00e7\u00e3o do PNPG\u201d.<\/p>\n<p>Ao abrigo daquele protocolo, o concelho de Arcos de Valdevez passou a dispor de um abrigo de montanha criado nos antigos quart\u00e9is do santu\u00e1rio de Nossa Senhora da Peneda, na Gavieira.<\/p>\n<p>Atualmente em processo de classifica\u00e7\u00e3o nacional, o templo da Senhora da Peneda, datado do s\u00e9culo XVIII, foi elevado a santu\u00e1rio, em abril 2020, por decreto do ent\u00e3o bispo da Diocese de Viana do Castelo, Anacleto Oliveira, que morreu, em setembro, num acidente de via\u00e7\u00e3o.<\/p>\n<p>A reconvers\u00e3o dos antigos quart\u00e9is, inaugurada na segunda-feira, representou um investimento de 120 mil euros.<\/p>\n<p>O abrigo, com capacidade para acolher 28 pessoas, repartidas por duas camaratas, resultou de uma parceria com a Confraria de Nossa Senhora da Peneda.<\/p>\n<p>Al\u00e9m de servir de abrigo aos romeiros da Via Mariana luso-galaica, o espa\u00e7o pretende dar \u201cabrigo \u00e0s pessoas que fazem escaladas, no Penedo da Meadinha, junto ao santu\u00e1rio da Senhora da Peneda, um dos locais mais procurados da zona norte para a pr\u00e1tica daquela modalidade\u201d.<\/p>\n<p>\u201c\u00c9 um espa\u00e7o que permite alojar os romeiros da Peneda, da Via Mariana, os turistas e os montanhistas que fa\u00e7am a travessia do PNPG ou escolham o local para pr\u00e1tica de escalada e outras atividades de montanha\u201d, apontou.<\/p>\n<p>Jo\u00e3o Manuel Esteves adiantou que o abrigo de montanha de Arcos de Valdevez \u201c\u00e9 um dos cinco previstos no protocolo celebrado pelo Fundo Ambiental com as autarquias da \u00e1rea do PNPG para a melhoria das condi\u00e7\u00f5es de visita\u00e7\u00e3o do territ\u00f3rio\u201d.<\/p>\n<p>\u201cPedimos para este protocolo ser refor\u00e7ado, para melhoramos as acessibilidades e a seguran\u00e7a da visita\u00e7\u00e3o de determinados locais no interior do parque\u201d, real\u00e7ou.<\/p>\n<p>A Via Mariana Luso-Galaica, que liga a Bas\u00edlica do Sameiro, em Braga, ao Santu\u00e1rio da Virgem da Barca, em Muxia, passa por cerca de uma dezena de santu\u00e1rios marianos do Minho e da Galiza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente da Comiss\u00e3o de Cogest\u00e3o do Parque Nacional da Peneda-Ger\u00eas (PNPG) defendeu a cria\u00e7\u00e3o naquele territ\u00f3rio de uma Interven\u00e7\u00e3o Territorial Integrada (ITI), um mecanismo que permitir\u00e1 agilizar o acesso a fundos comunit\u00e1rios. Em declara\u00e7\u00f5es \u00e0 ag\u00eancia Lusa, a prop\u00f3sito dos 51 anos do PNPG, assinalados na segunda-feira, numa sess\u00e3o\u00a0na Gavieira, em Arcos de Valdevez, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":18766,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[2],"tags":[27],"class_list":["post-79654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arcos-de-valdevez","tag-sociedade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Parque Nacional Peneda Ger\u00eas quer mecanismo que agilize acesso a fundos comunit\u00e1rios<\/title>\n<meta name=\"description\" content=\"O presidente da Comiss\u00e3o de Cogest\u00e3o do Parque Nacional da Peneda-Ger\u00eas defendeu a cria\u00e7\u00e3o naquele territ\u00f3rio de uma Interven\u00e7\u00e3o Territorial Integrada .\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parque Nacional Peneda Ger\u00eas quer mecanismo que agilize acesso a fundos comunit\u00e1rios\" \/>\n<meta property=\"og:description\" content=\"O presidente da Comiss\u00e3o de Cogest\u00e3o do Parque Nacional da Peneda-Ger\u00eas defendeu a cria\u00e7\u00e3o naquele territ\u00f3rio de uma Interven\u00e7\u00e3o Territorial Integrada .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Altominho.tv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/altominhotv\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-11T08:52:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-11T08:52:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2018\/09\/Parque-Nacional-Peneda-Gere\u0302s.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lusa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:site\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lusa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/\"},\"author\":{\"name\":\"Lusa\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/63f693da3e1899361cbe955c46f3232e\"},\"headline\":\"Parque Nacional Peneda Ger\u00eas quer mecanismo que agilize acesso a fundos comunit\u00e1rios\",\"datePublished\":\"2022-05-11T08:52:20+00:00\",\"dateModified\":\"2022-05-11T08:52:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/\"},\"wordCount\":631,\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Parque-Nacional-Peneda-Gere\u0302s.jpg\",\"keywords\":[\"Sociedade\"],\"articleSection\":[\"Arcos de Valdevez\"],\"inLanguage\":\"pt-PT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/\",\"name\":\"Parque Nacional Peneda Ger\u00eas quer mecanismo que agilize acesso a fundos comunit\u00e1rios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Parque-Nacional-Peneda-Gere\u0302s.jpg\",\"datePublished\":\"2022-05-11T08:52:20+00:00\",\"dateModified\":\"2022-05-11T08:52:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/63f693da3e1899361cbe955c46f3232e\"},\"description\":\"O presidente da Comiss\u00e3o de Cogest\u00e3o do Parque Nacional da Peneda-Ger\u00eas defendeu a cria\u00e7\u00e3o naquele territ\u00f3rio de uma Interven\u00e7\u00e3o Territorial Integrada .\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Parque-Nacional-Peneda-Gere\u0302s.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Parque-Nacional-Peneda-Gere\u0302s.jpg\",\"width\":1200,\"height\":900,\"caption\":\"DESCUBRA MINHO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2022\\\/05\\\/11\\\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parque Nacional Peneda Ger\u00eas quer mecanismo que agilize acesso a fundos comunit\u00e1rios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\",\"name\":\"Altominho.tv\",\"description\":\"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/63f693da3e1899361cbe955c46f3232e\",\"name\":\"Lusa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/LUSA_Logo.gif\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/LUSA_Logo.gif\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/LUSA_Logo.gif\",\"caption\":\"Lusa\"},\"sameAs\":[\"http:\\\/\\\/\\\/\\\/www.altominho.tv\\\/site\"],\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/author\\\/lusa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Parque Nacional Peneda Ger\u00eas quer mecanismo que agilize acesso a fundos comunit\u00e1rios","description":"O presidente da Comiss\u00e3o de Cogest\u00e3o do Parque Nacional da Peneda-Ger\u00eas defendeu a cria\u00e7\u00e3o naquele territ\u00f3rio de uma Interven\u00e7\u00e3o Territorial Integrada .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/","og_locale":"pt_PT","og_type":"article","og_title":"Parque Nacional Peneda Ger\u00eas quer mecanismo que agilize acesso a fundos comunit\u00e1rios","og_description":"O presidente da Comiss\u00e3o de Cogest\u00e3o do Parque Nacional da Peneda-Ger\u00eas defendeu a cria\u00e7\u00e3o naquele territ\u00f3rio de uma Interven\u00e7\u00e3o Territorial Integrada .","og_url":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/","og_site_name":"Altominho.tv","article_publisher":"https:\/\/www.facebook.com\/altominhotv","article_published_time":"2022-05-11T08:52:20+00:00","article_modified_time":"2022-05-11T08:52:25+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2018\/09\/Parque-Nacional-Peneda-Gere\u0302s.jpg","type":"image\/jpeg"}],"author":"Lusa","twitter_card":"summary_large_image","twitter_creator":"@altominhoTV","twitter_site":"@altominhoTV","twitter_misc":{"Escrito por":"Lusa","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/#article","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/"},"author":{"name":"Lusa","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/63f693da3e1899361cbe955c46f3232e"},"headline":"Parque Nacional Peneda Ger\u00eas quer mecanismo que agilize acesso a fundos comunit\u00e1rios","datePublished":"2022-05-11T08:52:20+00:00","dateModified":"2022-05-11T08:52:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/"},"wordCount":631,"image":{"@id":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2018\/09\/Parque-Nacional-Peneda-Gere\u0302s.jpg","keywords":["Sociedade"],"articleSection":["Arcos de Valdevez"],"inLanguage":"pt-PT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.altominho.tv\/site\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/","url":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/","name":"Parque Nacional Peneda Ger\u00eas quer mecanismo que agilize acesso a fundos comunit\u00e1rios","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/#primaryimage"},"image":{"@id":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2018\/09\/Parque-Nacional-Peneda-Gere\u0302s.jpg","datePublished":"2022-05-11T08:52:20+00:00","dateModified":"2022-05-11T08:52:25+00:00","author":{"@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/63f693da3e1899361cbe955c46f3232e"},"description":"O presidente da Comiss\u00e3o de Cogest\u00e3o do Parque Nacional da Peneda-Ger\u00eas defendeu a cria\u00e7\u00e3o naquele territ\u00f3rio de uma Interven\u00e7\u00e3o Territorial Integrada .","breadcrumb":{"@id":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/#primaryimage","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2018\/09\/Parque-Nacional-Peneda-Gere\u0302s.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2018\/09\/Parque-Nacional-Peneda-Gere\u0302s.jpg","width":1200,"height":900,"caption":"DESCUBRA MINHO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.altominho.tv\/site\/2022\/05\/11\/parque-nacional-peneda-geres-quer-mecanismo-que-agilize-acesso-a-fundos-comunitarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.altominho.tv\/site\/"},{"@type":"ListItem","position":2,"name":"Parque Nacional Peneda Ger\u00eas quer mecanismo que agilize acesso a fundos comunit\u00e1rios"}]},{"@type":"WebSite","@id":"https:\/\/www.altominho.tv\/site\/#website","url":"https:\/\/www.altominho.tv\/site\/","name":"Altominho.tv","description":"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.altominho.tv\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/63f693da3e1899361cbe955c46f3232e","name":"Lusa","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/08\/LUSA_Logo.gif","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/08\/LUSA_Logo.gif","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/08\/LUSA_Logo.gif","caption":"Lusa"},"sameAs":["http:\/\/\/\/www.altominho.tv\/site"],"url":"https:\/\/www.altominho.tv\/site\/author\/lusa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/79654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/comments?post=79654"}],"version-history":[{"count":0,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/79654\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media\/18766"}],"wp:attachment":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media?parent=79654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/categories?post=79654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/tags?post=79654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}