{"id":61744,"date":"2021-02-09T18:50:24","date_gmt":"2021-02-09T18:50:24","guid":{"rendered":"https:\/\/www.altominho.tv\/site\/?p=61744"},"modified":"2021-02-09T18:50:28","modified_gmt":"2021-02-09T18:50:28","slug":"municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas","status":"publish","type":"post","link":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/","title":{"rendered":"Munic\u00edpio de Arcos de Valdevez entrega 130 computadores \u00e0s escolas"},"content":{"rendered":"<p>O munic\u00edpio de Arcos de Valdevez entregou mais 120 computadores ao agrupamento de escolas do concelho, que se juntam aos 10 que j\u00e1 tinham sido entregues no \u00e2mbito da parceria com os Empreendimentos E\u00f3licos do Vale do Minho.<\/p>\n<p>Em comunicado, a autarquia sublinha que pretende &#8220;apoiar os alunos e as fam\u00edlias mais vulner\u00e1veis, para garantir a igualdade no acesso \u00e0 educa\u00e7\u00e3o a todos os alunos&#8221;, no \u00e2mbito do &#8220;novo modelo de ensino \u00e0 dist\u00e2ncia atrav\u00e9s do computador e internet&#8221;.<\/p>\n<p>&#8220;Com este apoio perfaz-se um total de cerca de 100 mil euros no apoio ao ensino \u00e0 dist\u00e2ncia, uma vez que vem complementar os dois protocolos de apoio de cerca de 60 mil euros atribu\u00eddos \u00e0 Associa\u00e7\u00e3o de Pais e Encarregados de Educa\u00e7\u00e3o e ao Agrupamento de Escolas de Valdevez, no primeiro per\u00edodo de confinamento&#8221;, refere o munic\u00edpio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O munic\u00edpio de Arcos de Valdevez entregou mais 120 computadores ao agrupamento de escolas do concelho, que se juntam aos 10 que j\u00e1 tinham sido entregues no \u00e2mbito da parceria com os Empreendimentos E\u00f3licos do Vale do Minho. Em comunicado, a autarquia sublinha que pretende &#8220;apoiar os alunos e as fam\u00edlias mais vulner\u00e1veis, para garantir [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":61745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[22],"class_list":["post-61744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arcos-de-valdevez","tag-educacao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Munic\u00edpio de Arcos de Valdevez entrega 130 computadores \u00e0s escolas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Munic\u00edpio de Arcos de Valdevez entrega 130 computadores \u00e0s escolas\" \/>\n<meta property=\"og:description\" content=\"O munic\u00edpio de Arcos de Valdevez entregou mais 120 computadores ao agrupamento de escolas do concelho, que se juntam aos 10 que j\u00e1 tinham sido entregues no \u00e2mbito da parceria com os Empreendimentos E\u00f3licos do Vale do Minho. Em comunicado, a autarquia sublinha que pretende &#8220;apoiar os alunos e as fam\u00edlias mais vulner\u00e1veis, para garantir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/\" \/>\n<meta property=\"og:site_name\" content=\"Altominho.tv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/altominhotv\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-09T18:50:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-09T18:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/02\/Computadores-Arcos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"841\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andreia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:site\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/\"},\"author\":{\"name\":\"Andreia Ferreira\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/d9be4265364723f14ea8e0d56a1d38cd\"},\"headline\":\"Munic\u00edpio de Arcos de Valdevez entrega 130 computadores \u00e0s escolas\",\"datePublished\":\"2021-02-09T18:50:24+00:00\",\"dateModified\":\"2021-02-09T18:50:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/\"},\"wordCount\":152,\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Computadores-Arcos.jpg\",\"keywords\":[\"Educa\u00e7\u00e3o\"],\"articleSection\":[\"Arcos de Valdevez\"],\"inLanguage\":\"pt-PT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/\",\"name\":\"Munic\u00edpio de Arcos de Valdevez entrega 130 computadores \u00e0s escolas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Computadores-Arcos.jpg\",\"datePublished\":\"2021-02-09T18:50:24+00:00\",\"dateModified\":\"2021-02-09T18:50:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/d9be4265364723f14ea8e0d56a1d38cd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Computadores-Arcos.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Computadores-Arcos.jpg\",\"width\":1620,\"height\":841},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2021\\\/02\\\/09\\\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Munic\u00edpio de Arcos de Valdevez entrega 130 computadores \u00e0s escolas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\",\"name\":\"Altominho.tv\",\"description\":\"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/d9be4265364723f14ea8e0d56a1d38cd\",\"name\":\"Andreia Ferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/AndreiaFerreira-150x150.jpg\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/AndreiaFerreira-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/AndreiaFerreira-150x150.jpg\",\"caption\":\"Andreia Ferreira\"},\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/author\\\/andreiaferreira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Munic\u00edpio de Arcos de Valdevez entrega 130 computadores \u00e0s escolas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/","og_locale":"pt_PT","og_type":"article","og_title":"Munic\u00edpio de Arcos de Valdevez entrega 130 computadores \u00e0s escolas","og_description":"O munic\u00edpio de Arcos de Valdevez entregou mais 120 computadores ao agrupamento de escolas do concelho, que se juntam aos 10 que j\u00e1 tinham sido entregues no \u00e2mbito da parceria com os Empreendimentos E\u00f3licos do Vale do Minho. Em comunicado, a autarquia sublinha que pretende &#8220;apoiar os alunos e as fam\u00edlias mais vulner\u00e1veis, para garantir [&hellip;]","og_url":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/","og_site_name":"Altominho.tv","article_publisher":"https:\/\/www.facebook.com\/altominhotv","article_published_time":"2021-02-09T18:50:24+00:00","article_modified_time":"2021-02-09T18:50:28+00:00","og_image":[{"width":1620,"height":841,"url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/02\/Computadores-Arcos.jpg","type":"image\/jpeg"}],"author":"Andreia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@altominhoTV","twitter_site":"@altominhoTV","twitter_misc":{"Escrito por":"Andreia Ferreira","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/#article","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/"},"author":{"name":"Andreia Ferreira","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/d9be4265364723f14ea8e0d56a1d38cd"},"headline":"Munic\u00edpio de Arcos de Valdevez entrega 130 computadores \u00e0s escolas","datePublished":"2021-02-09T18:50:24+00:00","dateModified":"2021-02-09T18:50:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/"},"wordCount":152,"image":{"@id":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/02\/Computadores-Arcos.jpg","keywords":["Educa\u00e7\u00e3o"],"articleSection":["Arcos de Valdevez"],"inLanguage":"pt-PT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.altominho.tv\/site\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/","url":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/","name":"Munic\u00edpio de Arcos de Valdevez entrega 130 computadores \u00e0s escolas","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/#primaryimage"},"image":{"@id":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/02\/Computadores-Arcos.jpg","datePublished":"2021-02-09T18:50:24+00:00","dateModified":"2021-02-09T18:50:28+00:00","author":{"@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/d9be4265364723f14ea8e0d56a1d38cd"},"breadcrumb":{"@id":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/#primaryimage","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/02\/Computadores-Arcos.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/02\/Computadores-Arcos.jpg","width":1620,"height":841},{"@type":"BreadcrumbList","@id":"https:\/\/www.altominho.tv\/site\/2021\/02\/09\/municipio-de-arcos-de-valdevez-entrega-130-computadores-as-escolas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.altominho.tv\/site\/"},{"@type":"ListItem","position":2,"name":"Munic\u00edpio de Arcos de Valdevez entrega 130 computadores \u00e0s escolas"}]},{"@type":"WebSite","@id":"https:\/\/www.altominho.tv\/site\/#website","url":"https:\/\/www.altominho.tv\/site\/","name":"Altominho.tv","description":"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.altominho.tv\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/d9be4265364723f14ea8e0d56a1d38cd","name":"Andreia Ferreira","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/01\/AndreiaFerreira-150x150.jpg","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/01\/AndreiaFerreira-150x150.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/01\/AndreiaFerreira-150x150.jpg","caption":"Andreia Ferreira"},"url":"https:\/\/www.altominho.tv\/site\/author\/andreiaferreira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/61744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/comments?post=61744"}],"version-history":[{"count":0,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/61744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media\/61745"}],"wp:attachment":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media?parent=61744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/categories?post=61744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/tags?post=61744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}