{"id":27455,"date":"2019-04-18T17:04:44","date_gmt":"2019-04-18T16:04:44","guid":{"rendered":"http:\/\/www.altominho.tv\/site\/?p=27455"},"modified":"2019-04-18T17:04:44","modified_gmt":"2019-04-18T16:04:44","slug":"viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit","status":"publish","type":"post","link":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/","title":{"rendered":"Viana do Castelo defende corredor atl\u00e2ntico para fazer face a cen\u00e1rio p\u00f3s-Brexit"},"content":{"rendered":"<p>O presidente da C\u00e2mara de Viana do Castelo defendeu um corredor Atl\u00e2ntico ferrovi\u00e1rio a ligar os portos portugueses aos do norte de Espanha e Fran\u00e7a, at\u00e9 \u00e0 Normandia para fazer face a um cen\u00e1rio p\u00f3s-Brexit.<\/p>\n<p>Em comunicado, a autarquia adiantou que para Jos\u00e9 Maria Costa, que participou, em Dublin, num semin\u00e1rio promovido pela Comiss\u00e3o Europeia sobre as liga\u00e7\u00f5es entre portos e cidades na bacia Atl\u00e2ntica, a possibilidade de sa\u00edda do Reino Unido da Uni\u00e3o Europeia &#8220;torna ainda mais urgente um refor\u00e7o da coopera\u00e7\u00e3o entre as cidades e os portos do Atl\u00e2ntico&#8221;.<\/p>\n<p>&#8220;\u00c9 necess\u00e1rio que a Comiss\u00e3o Europeia, no \u00e2mbito do processo de revis\u00e3o da RTE-T &#8220;Rede Transfronteiri\u00e7a de Transportes&#8221; identifique o corredor Atl\u00e2ntico ferrovi\u00e1rio que liga os portos portugueses aos portos do Norte de Espanha e portos franceses at\u00e9 \u00e0 Normandia&#8221;, sustentou.<\/p>\n<p>O autarca, que participou numa mesa redonda dirigida pelo coordenador europeu do corredor Atl\u00e2ntico, referiu que aquela liga\u00e7\u00e3o &#8220;tem como primeiro objetivo promover uma extens\u00e3o real destas liga\u00e7\u00f5es ferrovi\u00e1rias a portos da Irlanda atrav\u00e9s dos portos da Bretanha e Normandia&#8221;.<\/p>\n<p>Jos\u00e9 Maria Costa defendeu &#8220;uma perspetiva europeia para o corredor Atl\u00e2ntico em que se torna priorit\u00e1rio um planeamento e um tratamento pol\u00edtico deste corredor por parte dos governos de Portugal e Espanha&#8221;.<\/p>\n<p>&#8220;Desta forma garante-se que toda a fachada atl\u00e2ntica ib\u00e9rica n\u00e3o ficar\u00e1 de fora das grandes conex\u00f5es portu\u00e1rias e ferrovi\u00e1rias do futuro da Europa&#8221;, frisou.<\/p>\n<p>A miss\u00e3o do corredor Atl\u00e2ntico &#8220;assenta, num primeiro plano, na rentabiliza\u00e7\u00e3o da infraestrutura ferrovi\u00e1ria existente, sem investimento adicional, atrav\u00e9s de uma gest\u00e3o centralizada da atribui\u00e7\u00e3o de capacidade, da gest\u00e3o de tr\u00e1fego e do relacionamento com os clientes&#8221;.<\/p>\n<p>O corredor Atl\u00e2ntico &#8220;assume-se tamb\u00e9m como plataforma privilegiada para a coordena\u00e7\u00e3o dos investimentos na infraestrutura ferrovi\u00e1ria em Portugal, Espanha, Fran\u00e7a e Alemanha, no sentido de serem ultrapassadas barreiras t\u00e9cnicas e operacionais, promovendo a interoperabilidade e, consequentemente, fomentando uma maior competitividade do transporte ferrovi\u00e1rio de mercadorias&#8221;.<\/p>\n<p>No semin\u00e1rio que decorreu ter\u00e7a e quarta-feira em Dublin, participaram respons\u00e1veis europeus da estrat\u00e9gia mar\u00edtima atl\u00e2ntica, dos portos do Norte da Europa, de Espanha, do B\u00e1ltico e tamb\u00e9m da Associa\u00e7\u00e3o da Autoridade de Energia Renov\u00e1vel da Irlanda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente da C\u00e2mara de Viana do Castelo defendeu um corredor Atl\u00e2ntico ferrovi\u00e1rio a ligar os portos portugueses aos do norte de Espanha e Fran\u00e7a, at\u00e9 \u00e0 Normandia para fazer face a um cen\u00e1rio p\u00f3s-Brexit. Em comunicado, a autarquia adiantou que para Jos\u00e9 Maria Costa, que participou, em Dublin, num semin\u00e1rio promovido pela Comiss\u00e3o Europeia [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":27456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[14],"tags":[27],"class_list":["post-27455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viana-do-castelo","tag-sociedade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Viana do Castelo defende corredor atl\u00e2ntico para fazer face a cen\u00e1rio p\u00f3s-Brexit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viana do Castelo defende corredor atl\u00e2ntico para fazer face a cen\u00e1rio p\u00f3s-Brexit\" \/>\n<meta property=\"og:description\" content=\"O presidente da C\u00e2mara de Viana do Castelo defendeu um corredor Atl\u00e2ntico ferrovi\u00e1rio a ligar os portos portugueses aos do norte de Espanha e Fran\u00e7a, at\u00e9 \u00e0 Normandia para fazer face a um cen\u00e1rio p\u00f3s-Brexit. Em comunicado, a autarquia adiantou que para Jos\u00e9 Maria Costa, que participou, em Dublin, num semin\u00e1rio promovido pela Comiss\u00e3o Europeia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/\" \/>\n<meta property=\"og:site_name\" content=\"Altominho.tv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/altominhotv\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-18T16:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/04\/dublin_presidente-e1555603354201.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andreia Ferreira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:site\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreia Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/\"},\"author\":{\"name\":\"Andreia Ferreira\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/d9be4265364723f14ea8e0d56a1d38cd\"},\"headline\":\"Viana do Castelo defende corredor atl\u00e2ntico para fazer face a cen\u00e1rio p\u00f3s-Brexit\",\"datePublished\":\"2019-04-18T16:04:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/\"},\"wordCount\":421,\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/dublin_presidente-e1555603354201.jpg\",\"keywords\":[\"Sociedade\"],\"articleSection\":[\"Viana do Castelo\"],\"inLanguage\":\"pt-PT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/\",\"name\":\"Viana do Castelo defende corredor atl\u00e2ntico para fazer face a cen\u00e1rio p\u00f3s-Brexit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/dublin_presidente-e1555603354201.jpg\",\"datePublished\":\"2019-04-18T16:04:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/d9be4265364723f14ea8e0d56a1d38cd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/dublin_presidente-e1555603354201.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/dublin_presidente-e1555603354201.jpg\",\"width\":768,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2019\\\/04\\\/18\\\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viana do Castelo defende corredor atl\u00e2ntico para fazer face a cen\u00e1rio p\u00f3s-Brexit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\",\"name\":\"Altominho.tv\",\"description\":\"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/d9be4265364723f14ea8e0d56a1d38cd\",\"name\":\"Andreia Ferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/AndreiaFerreira-150x150.jpg\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/AndreiaFerreira-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/AndreiaFerreira-150x150.jpg\",\"caption\":\"Andreia Ferreira\"},\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/author\\\/andreiaferreira\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Viana do Castelo defende corredor atl\u00e2ntico para fazer face a cen\u00e1rio p\u00f3s-Brexit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/","og_locale":"pt_PT","og_type":"article","og_title":"Viana do Castelo defende corredor atl\u00e2ntico para fazer face a cen\u00e1rio p\u00f3s-Brexit","og_description":"O presidente da C\u00e2mara de Viana do Castelo defendeu um corredor Atl\u00e2ntico ferrovi\u00e1rio a ligar os portos portugueses aos do norte de Espanha e Fran\u00e7a, at\u00e9 \u00e0 Normandia para fazer face a um cen\u00e1rio p\u00f3s-Brexit. Em comunicado, a autarquia adiantou que para Jos\u00e9 Maria Costa, que participou, em Dublin, num semin\u00e1rio promovido pela Comiss\u00e3o Europeia [&hellip;]","og_url":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/","og_site_name":"Altominho.tv","article_publisher":"https:\/\/www.facebook.com\/altominhotv","article_published_time":"2019-04-18T16:04:44+00:00","og_image":[{"width":768,"height":487,"url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/04\/dublin_presidente-e1555603354201.jpg","type":"image\/jpeg"}],"author":"Andreia Ferreira","twitter_card":"summary_large_image","twitter_creator":"@altominhoTV","twitter_site":"@altominhoTV","twitter_misc":{"Escrito por":"Andreia Ferreira","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/#article","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/"},"author":{"name":"Andreia Ferreira","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/d9be4265364723f14ea8e0d56a1d38cd"},"headline":"Viana do Castelo defende corredor atl\u00e2ntico para fazer face a cen\u00e1rio p\u00f3s-Brexit","datePublished":"2019-04-18T16:04:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/"},"wordCount":421,"image":{"@id":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/04\/dublin_presidente-e1555603354201.jpg","keywords":["Sociedade"],"articleSection":["Viana do Castelo"],"inLanguage":"pt-PT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.altominho.tv\/site\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/","url":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/","name":"Viana do Castelo defende corredor atl\u00e2ntico para fazer face a cen\u00e1rio p\u00f3s-Brexit","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/#primaryimage"},"image":{"@id":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/04\/dublin_presidente-e1555603354201.jpg","datePublished":"2019-04-18T16:04:44+00:00","author":{"@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/d9be4265364723f14ea8e0d56a1d38cd"},"breadcrumb":{"@id":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/#primaryimage","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/04\/dublin_presidente-e1555603354201.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/04\/dublin_presidente-e1555603354201.jpg","width":768,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/www.altominho.tv\/site\/2019\/04\/18\/viana-do-castelo-defende-corredor-atlantico-para-fazer-face-a-cenario-pos-brexit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.altominho.tv\/site\/"},{"@type":"ListItem","position":2,"name":"Viana do Castelo defende corredor atl\u00e2ntico para fazer face a cen\u00e1rio p\u00f3s-Brexit"}]},{"@type":"WebSite","@id":"https:\/\/www.altominho.tv\/site\/#website","url":"https:\/\/www.altominho.tv\/site\/","name":"Altominho.tv","description":"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.altominho.tv\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/d9be4265364723f14ea8e0d56a1d38cd","name":"Andreia Ferreira","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/01\/AndreiaFerreira-150x150.jpg","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/01\/AndreiaFerreira-150x150.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/01\/AndreiaFerreira-150x150.jpg","caption":"Andreia Ferreira"},"url":"https:\/\/www.altominho.tv\/site\/author\/andreiaferreira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/27455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/comments?post=27455"}],"version-history":[{"count":0,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/27455\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media\/27456"}],"wp:attachment":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media?parent=27455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/categories?post=27455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/tags?post=27455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}