{"id":126113,"date":"2025-12-11T15:20:37","date_gmt":"2025-12-11T15:20:37","guid":{"rendered":"https:\/\/www.altominho.tv\/site\/?p=126113"},"modified":"2025-12-11T15:21:32","modified_gmt":"2025-12-11T15:21:32","slug":"militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica","status":"publish","type":"post","link":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/","title":{"rendered":"Militar da GNR fora de servi\u00e7o agredido violentamente com ferramenta na via p\u00fablica"},"content":{"rendered":"<p data-start=\"76\" data-end=\"353\">Um militar da GNR, que se encontrava fora de servi\u00e7o, foi agredido na noite de ontem nas imedia\u00e7\u00f5es da Escola Superior de Ci\u00eancias Empresariais de Valen\u00e7a.<\/p>\n<p data-start=\"76\" data-end=\"353\">De acordo com informa\u00e7\u00f5es recolhidas pela <strong>Altominho TV<\/strong>, a agress\u00e3o ter\u00e1 sido perpetrada por, pelo menos, dois indiv\u00edduos.<\/p>\n<p data-start=\"355\" data-end=\"712\">Segundo a mesma fonte, os agressores utilizaram uma ferramenta descrita como \u201cuma esp\u00e9cie de chave de fendas\u201d, provocando v\u00e1rios ferimentos na face do militar. A v\u00edtima foi assistida no local e transportada posteriormente para o Hospital de Santa Luzia, em Viana do Castelo, apresentando ferimentos considerados ligeiros. O militar recebeu alta ap\u00f3s avalia\u00e7\u00e3o m\u00e9dica.<\/p>\n<p data-start=\"714\" data-end=\"849\" data-is-last-node=\"\" data-is-only-node=\"\">A Pol\u00edcia Judici\u00e1ria est\u00e1 agora a investigar o caso, procurando apurar as circunst\u00e2ncias da agress\u00e3o e identificar todos os envolvidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um militar da GNR, que se encontrava fora de servi\u00e7o, foi agredido na noite de ontem nas imedia\u00e7\u00f5es da Escola Superior de Ci\u00eancias Empresariais de Valen\u00e7a. De acordo com informa\u00e7\u00f5es recolhidas pela Altominho TV, a agress\u00e3o ter\u00e1 sido perpetrada por, pelo menos, dois indiv\u00edduos. Segundo a mesma fonte, os agressores utilizaram uma ferramenta descrita como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":126115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[13],"tags":[27],"class_list":["post-126113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valenca","tag-sociedade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Militar da GNR fora de servi\u00e7o agredido violentamente com ferramenta na via p\u00fablica<\/title>\n<meta name=\"description\" content=\"Um militar da GNR, que se encontrava fora de servi\u00e7o, foi agredido na noite de ontem nas imedia\u00e7\u00f5es da Escola Superior de Ci\u00eancias Empresariais de Valen\u00e7a.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Militar da GNR fora de servi\u00e7o agredido violentamente com ferramenta na via p\u00fablica\" \/>\n<meta property=\"og:description\" content=\"Um militar da GNR, que se encontrava fora de servi\u00e7o, foi agredido na noite de ontem nas imedia\u00e7\u00f5es da Escola Superior de Ci\u00eancias Empresariais de Valen\u00e7a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/\" \/>\n<meta property=\"og:site_name\" content=\"Altominho.tv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/altominhotv\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-11T15:20:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-11T15:21:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/12\/agressao-na-rua.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Altominho.tv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:site\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Altominho.tv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/\"},\"author\":{\"name\":\"Altominho.tv\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\"},\"headline\":\"Militar da GNR fora de servi\u00e7o agredido violentamente com ferramenta na via p\u00fablica\",\"datePublished\":\"2025-12-11T15:20:37+00:00\",\"dateModified\":\"2025-12-11T15:21:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/\"},\"wordCount\":150,\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/agressao-na-rua.jpg\",\"keywords\":[\"Sociedade\"],\"articleSection\":[\"Valen\u00e7a\"],\"inLanguage\":\"pt-PT\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/\",\"name\":\"Militar da GNR fora de servi\u00e7o agredido violentamente com ferramenta na via p\u00fablica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/agressao-na-rua.jpg\",\"datePublished\":\"2025-12-11T15:20:37+00:00\",\"dateModified\":\"2025-12-11T15:21:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\"},\"description\":\"Um militar da GNR, que se encontrava fora de servi\u00e7o, foi agredido na noite de ontem nas imedia\u00e7\u00f5es da Escola Superior de Ci\u00eancias Empresariais de Valen\u00e7a.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/agressao-na-rua.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/agressao-na-rua.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/12\\\/11\\\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Militar da GNR fora de servi\u00e7o agredido violentamente com ferramenta na via p\u00fablica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\",\"name\":\"Altominho.tv\",\"description\":\"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\",\"name\":\"Altominho.tv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"caption\":\"Altominho.tv\"},\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/author\\\/altominhotv-tecnico\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Militar da GNR fora de servi\u00e7o agredido violentamente com ferramenta na via p\u00fablica","description":"Um militar da GNR, que se encontrava fora de servi\u00e7o, foi agredido na noite de ontem nas imedia\u00e7\u00f5es da Escola Superior de Ci\u00eancias Empresariais de Valen\u00e7a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/","og_locale":"pt_PT","og_type":"article","og_title":"Militar da GNR fora de servi\u00e7o agredido violentamente com ferramenta na via p\u00fablica","og_description":"Um militar da GNR, que se encontrava fora de servi\u00e7o, foi agredido na noite de ontem nas imedia\u00e7\u00f5es da Escola Superior de Ci\u00eancias Empresariais de Valen\u00e7a.","og_url":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/","og_site_name":"Altominho.tv","article_publisher":"https:\/\/www.facebook.com\/altominhotv","article_published_time":"2025-12-11T15:20:37+00:00","article_modified_time":"2025-12-11T15:21:32+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/12\/agressao-na-rua.jpg","type":"image\/jpeg"}],"author":"Altominho.tv","twitter_card":"summary_large_image","twitter_creator":"@altominhoTV","twitter_site":"@altominhoTV","twitter_misc":{"Escrito por":"Altominho.tv","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/#article","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/"},"author":{"name":"Altominho.tv","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22"},"headline":"Militar da GNR fora de servi\u00e7o agredido violentamente com ferramenta na via p\u00fablica","datePublished":"2025-12-11T15:20:37+00:00","dateModified":"2025-12-11T15:21:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/"},"wordCount":150,"image":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/12\/agressao-na-rua.jpg","keywords":["Sociedade"],"articleSection":["Valen\u00e7a"],"inLanguage":"pt-PT","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.altominho.tv\/site\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/","url":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/","name":"Militar da GNR fora de servi\u00e7o agredido violentamente com ferramenta na via p\u00fablica","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/#primaryimage"},"image":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/12\/agressao-na-rua.jpg","datePublished":"2025-12-11T15:20:37+00:00","dateModified":"2025-12-11T15:21:32+00:00","author":{"@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22"},"description":"Um militar da GNR, que se encontrava fora de servi\u00e7o, foi agredido na noite de ontem nas imedia\u00e7\u00f5es da Escola Superior de Ci\u00eancias Empresariais de Valen\u00e7a.","breadcrumb":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/#primaryimage","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/12\/agressao-na-rua.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/12\/agressao-na-rua.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.altominho.tv\/site\/2025\/12\/11\/militar-da-gnr-fora-de-servico-agredido-violentamente-com-ferramenta-na-via-publica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.altominho.tv\/site\/"},{"@type":"ListItem","position":2,"name":"Militar da GNR fora de servi\u00e7o agredido violentamente com ferramenta na via p\u00fablica"}]},{"@type":"WebSite","@id":"https:\/\/www.altominho.tv\/site\/#website","url":"https:\/\/www.altominho.tv\/site\/","name":"Altominho.tv","description":"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.altominho.tv\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22","name":"Altominho.tv","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","caption":"Altominho.tv"},"url":"https:\/\/www.altominho.tv\/site\/author\/altominhotv-tecnico\/"}]}},"_links":{"self":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/126113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/comments?post=126113"}],"version-history":[{"count":1,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/126113\/revisions"}],"predecessor-version":[{"id":126116,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/126113\/revisions\/126116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media\/126115"}],"wp:attachment":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media?parent=126113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/categories?post=126113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/tags?post=126113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}