{"id":123877,"date":"2025-10-10T11:03:19","date_gmt":"2025-10-10T10:03:19","guid":{"rendered":"https:\/\/www.altominho.tv\/site\/?p=123877"},"modified":"2025-10-10T11:03:22","modified_gmt":"2025-10-10T10:03:22","slug":"dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe","status":"publish","type":"post","link":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/","title":{"rendered":"DKC de Viana disputou 13 finais e estreou-se em SUP Canoe"},"content":{"rendered":"<p class=\"p1\">Os campeonatos nacionais de Regatas em Linha de Canoagem realizaram-se, mais uma vez, em Montemor-o-Velho. Este Centro de Alto Rendimento recebeu em duas datas distintas as respetivas competi\u00e7\u00f5es, uma destinado a seniores, juniores e Masters e outra destinada a iniciados, infantis e cadetes.<\/p>\n<p class=\"p1\">A DKC de Viana estreou nestes nacionais em seniores femininos a embarca\u00e7\u00e3o SUP Canoe, recentemente introduzida na canoagem federada nacional e internacional.<\/p>\n<p class=\"p1\">Mafalda Rodrigues, atleta da DKC, conquistou duas finais, tendo na sua melhor o 6\u00ba lugar nacional.\u00a0\u00a0Diana Silva tamb\u00e9m participou em SUP canoe.<\/p>\n<p class=\"p1\">Com uma delega\u00e7\u00e3o de 37 atletas de todos os escal\u00f5es, a DKC conseguiu alcan\u00e7ar 11 finais A e duas finais B, num total de 13 finais, com v\u00e1rias embarca\u00e7\u00f5es nos cinco primeiros lugares, sobretudo os atletas mais novos.<\/p>\n<p class=\"p1\">Destaque para Adriana Jooris, Dinis Veloso, o k4 cadete feminino e o C4 s\u00e9nior masculino que conquistaram cada um dele, respetivamente o 5\u00ba lugar nas finais A.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os campeonatos nacionais de Regatas em Linha de Canoagem realizaram-se, mais uma vez, em Montemor-o-Velho. Este Centro de Alto Rendimento recebeu em duas datas distintas as respetivas competi\u00e7\u00f5es, uma destinado a seniores, juniores e Masters e outra destinada a iniciados, infantis e cadetes. A DKC de Viana estreou nestes nacionais em seniores femininos a embarca\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":123878,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[14],"tags":[20],"class_list":["post-123877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viana-do-castelo","tag-desporto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>DKC de Viana disputou 13 finais e estreou-se em SUP Canoe<\/title>\n<meta name=\"description\" content=\"Os campeonatos nacionais de Regatas em Linha de Canoagem realizaram-se, mais uma vez, em Montemor-o-Velho. Este Centro de Alto Rendimento recebeu em duas datas distintas as respetivas competi\u00e7\u00f5es, uma destinado a seniores, juniores e Masters e outra destinada a iniciados, infantis e cadetes.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DKC de Viana disputou 13 finais e estreou-se em SUP Canoe\" \/>\n<meta property=\"og:description\" content=\"Os campeonatos nacionais de Regatas em Linha de Canoagem realizaram-se, mais uma vez, em Montemor-o-Velho. Este Centro de Alto Rendimento recebeu em duas datas distintas as respetivas competi\u00e7\u00f5es, uma destinado a seniores, juniores e Masters e outra destinada a iniciados, infantis e cadetes.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/\" \/>\n<meta property=\"og:site_name\" content=\"Altominho.tv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/altominhotv\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-10T10:03:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-10T10:03:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/Mafalda-Rodrigues.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Eduarda Cardoso\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:site\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduarda Cardoso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/\"},\"author\":{\"name\":\"Eduarda Cardoso\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/9e351387b727413d005ccf1152c93539\"},\"headline\":\"DKC de Viana disputou 13 finais e estreou-se em SUP Canoe\",\"datePublished\":\"2025-10-10T10:03:19+00:00\",\"dateModified\":\"2025-10-10T10:03:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/\"},\"wordCount\":167,\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Mafalda-Rodrigues.jpg\",\"keywords\":[\"Desporto\"],\"articleSection\":[\"Viana do Castelo\"],\"inLanguage\":\"pt-PT\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/\",\"name\":\"DKC de Viana disputou 13 finais e estreou-se em SUP Canoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Mafalda-Rodrigues.jpg\",\"datePublished\":\"2025-10-10T10:03:19+00:00\",\"dateModified\":\"2025-10-10T10:03:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/9e351387b727413d005ccf1152c93539\"},\"description\":\"Os campeonatos nacionais de Regatas em Linha de Canoagem realizaram-se, mais uma vez, em Montemor-o-Velho. Este Centro de Alto Rendimento recebeu em duas datas distintas as respetivas competi\u00e7\u00f5es, uma destinado a seniores, juniores e Masters e outra destinada a iniciados, infantis e cadetes.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Mafalda-Rodrigues.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Mafalda-Rodrigues.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/10\\\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DKC de Viana disputou 13 finais e estreou-se em SUP Canoe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\",\"name\":\"Altominho.tv\",\"description\":\"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/9e351387b727413d005ccf1152c93539\",\"name\":\"Eduarda Cardoso\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Logo-ATV_WEB-150x150.png\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Logo-ATV_WEB-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Logo-ATV_WEB-150x150.png\",\"caption\":\"Eduarda Cardoso\"},\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/author\\\/eduarda-cardoso\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"DKC de Viana disputou 13 finais e estreou-se em SUP Canoe","description":"Os campeonatos nacionais de Regatas em Linha de Canoagem realizaram-se, mais uma vez, em Montemor-o-Velho. Este Centro de Alto Rendimento recebeu em duas datas distintas as respetivas competi\u00e7\u00f5es, uma destinado a seniores, juniores e Masters e outra destinada a iniciados, infantis e cadetes.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/","og_locale":"pt_PT","og_type":"article","og_title":"DKC de Viana disputou 13 finais e estreou-se em SUP Canoe","og_description":"Os campeonatos nacionais de Regatas em Linha de Canoagem realizaram-se, mais uma vez, em Montemor-o-Velho. Este Centro de Alto Rendimento recebeu em duas datas distintas as respetivas competi\u00e7\u00f5es, uma destinado a seniores, juniores e Masters e outra destinada a iniciados, infantis e cadetes.\u00a0","og_url":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/","og_site_name":"Altominho.tv","article_publisher":"https:\/\/www.facebook.com\/altominhotv","article_published_time":"2025-10-10T10:03:19+00:00","article_modified_time":"2025-10-10T10:03:22+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/Mafalda-Rodrigues.jpg","type":"image\/jpeg"}],"author":"Eduarda Cardoso","twitter_card":"summary_large_image","twitter_creator":"@altominhoTV","twitter_site":"@altominhoTV","twitter_misc":{"Escrito por":"Eduarda Cardoso","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/#article","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/"},"author":{"name":"Eduarda Cardoso","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/9e351387b727413d005ccf1152c93539"},"headline":"DKC de Viana disputou 13 finais e estreou-se em SUP Canoe","datePublished":"2025-10-10T10:03:19+00:00","dateModified":"2025-10-10T10:03:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/"},"wordCount":167,"image":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/Mafalda-Rodrigues.jpg","keywords":["Desporto"],"articleSection":["Viana do Castelo"],"inLanguage":"pt-PT","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.altominho.tv\/site\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/","url":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/","name":"DKC de Viana disputou 13 finais e estreou-se em SUP Canoe","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/#primaryimage"},"image":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/Mafalda-Rodrigues.jpg","datePublished":"2025-10-10T10:03:19+00:00","dateModified":"2025-10-10T10:03:22+00:00","author":{"@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/9e351387b727413d005ccf1152c93539"},"description":"Os campeonatos nacionais de Regatas em Linha de Canoagem realizaram-se, mais uma vez, em Montemor-o-Velho. Este Centro de Alto Rendimento recebeu em duas datas distintas as respetivas competi\u00e7\u00f5es, uma destinado a seniores, juniores e Masters e outra destinada a iniciados, infantis e cadetes.\u00a0","breadcrumb":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/#primaryimage","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/Mafalda-Rodrigues.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/Mafalda-Rodrigues.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/10\/dkc-de-viana-disputou-13-finais-e-estreou-se-em-sup-canoe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.altominho.tv\/site\/"},{"@type":"ListItem","position":2,"name":"DKC de Viana disputou 13 finais e estreou-se em SUP Canoe"}]},{"@type":"WebSite","@id":"https:\/\/www.altominho.tv\/site\/#website","url":"https:\/\/www.altominho.tv\/site\/","name":"Altominho.tv","description":"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.altominho.tv\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/9e351387b727413d005ccf1152c93539","name":"Eduarda Cardoso","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/01\/cropped-Logo-ATV_WEB-150x150.png","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/01\/cropped-Logo-ATV_WEB-150x150.png","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2021\/01\/cropped-Logo-ATV_WEB-150x150.png","caption":"Eduarda Cardoso"},"url":"https:\/\/www.altominho.tv\/site\/author\/eduarda-cardoso\/"}]}},"_links":{"self":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/123877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/comments?post=123877"}],"version-history":[{"count":1,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/123877\/revisions"}],"predecessor-version":[{"id":123879,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/123877\/revisions\/123879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media\/123878"}],"wp:attachment":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media?parent=123877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/categories?post=123877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/tags?post=123877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}