{"id":123577,"date":"2025-10-02T16:43:57","date_gmt":"2025-10-02T15:43:57","guid":{"rendered":"https:\/\/www.altominho.tv\/site\/?p=123577"},"modified":"2025-10-02T16:44:03","modified_gmt":"2025-10-02T15:44:03","slug":"orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo","status":"publish","type":"post","link":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/","title":{"rendered":"Orcas provocam danos em veleiro brit\u00e2nico ao largo de Viana do Castelo"},"content":{"rendered":"<p data-start=\"168\" data-end=\"489\">Os tripulantes da Esta\u00e7\u00e3o Salva-vidas de Viana do Castelo auxiliaram esta quarta-feira tr\u00eas pessoas que seguiam a bordo de um veleiro com bandeira brit\u00e2nica, que sofreu danos no leme ap\u00f3s uma intera\u00e7\u00e3o com orcas, a cerca de nove milhas n\u00e1uticas (16,7 quil\u00f3metros) a sudoeste da barra de Viana do Castelo.<\/p>\n<p data-start=\"491\" data-end=\"757\">O alerta foi dado pelas 10h51 ao Centro de Coordena\u00e7\u00e3o de Busca e Salvamento Mar\u00edtimo de Lisboa (MRCC Lisboa), que acionou de imediato a Esta\u00e7\u00e3o Salva-vidas.<\/p>\n<p data-start=\"491\" data-end=\"757\">As tr\u00eas pessoas a bordo encontravam-se em boas condi\u00e7\u00f5es f\u00edsicas e n\u00e3o necessitaram de assist\u00eancia m\u00e9dica.<\/p>\n<p data-start=\"759\" data-end=\"1070\">Face \u00e0 avaria, o veleiro foi acompanhado at\u00e9 \u00e0 entrada da barra e posteriormente rebocado para a Marina de Viana do Castelo, de modo a garantir a seguran\u00e7a da navega\u00e7\u00e3o.<\/p>\n<p data-start=\"759\" data-end=\"1070\">A embarca\u00e7\u00e3o s\u00f3 poder\u00e1 retomar viagem ap\u00f3s vistoria t\u00e9cnica.<\/p>\n<p data-start=\"759\" data-end=\"1070\">O Comando Local da Pol\u00edcia Mar\u00edtima de Viana do Castelo registou a ocorr\u00eancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os tripulantes da Esta\u00e7\u00e3o Salva-vidas de Viana do Castelo auxiliaram esta quarta-feira tr\u00eas pessoas que seguiam a bordo de um veleiro com bandeira brit\u00e2nica, que sofreu danos no leme ap\u00f3s uma intera\u00e7\u00e3o com orcas, a cerca de nove milhas n\u00e1uticas (16,7 quil\u00f3metros) a sudoeste da barra de Viana do Castelo. O alerta foi dado pelas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":123578,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[14],"tags":[27],"class_list":["post-123577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viana-do-castelo","tag-sociedade"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Orcas provocam danos em veleiro brit\u00e2nico ao largo de Viana do Castelo<\/title>\n<meta name=\"description\" content=\"Os tripulantes da Esta\u00e7\u00e3o Salva-vidas de Viana do Castelo auxiliaram esta quarta-feira tr\u00eas pessoas que seguiam a bordo de um veleiro com bandeira brit\u00e2nica, que sofreu danos no leme ap\u00f3s uma intera\u00e7\u00e3o com orcas, a cerca de nove milhas n\u00e1uticas (16,7 quil\u00f3metros) a sudoeste da barra de Viana do Castelo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orcas provocam danos em veleiro brit\u00e2nico ao largo de Viana do Castelo\" \/>\n<meta property=\"og:description\" content=\"Os tripulantes da Esta\u00e7\u00e3o Salva-vidas de Viana do Castelo auxiliaram esta quarta-feira tr\u00eas pessoas que seguiam a bordo de um veleiro com bandeira brit\u00e2nica, que sofreu danos no leme ap\u00f3s uma intera\u00e7\u00e3o com orcas, a cerca de nove milhas n\u00e1uticas (16,7 quil\u00f3metros) a sudoeste da barra de Viana do Castelo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/\" \/>\n<meta property=\"og:site_name\" content=\"Altominho.tv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/altominhotv\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-02T15:43:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-02T15:44:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/estacao-salva-vidas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Altominho.tv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:site\" content=\"@altominhoTV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Altominho.tv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/\"},\"author\":{\"name\":\"Altominho.tv\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\"},\"headline\":\"Orcas provocam danos em veleiro brit\u00e2nico ao largo de Viana do Castelo\",\"datePublished\":\"2025-10-02T15:43:57+00:00\",\"dateModified\":\"2025-10-02T15:44:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/\"},\"wordCount\":178,\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/estacao-salva-vidas.jpg\",\"keywords\":[\"Sociedade\"],\"articleSection\":[\"Viana do Castelo\"],\"inLanguage\":\"pt-PT\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/\",\"name\":\"Orcas provocam danos em veleiro brit\u00e2nico ao largo de Viana do Castelo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/estacao-salva-vidas.jpg\",\"datePublished\":\"2025-10-02T15:43:57+00:00\",\"dateModified\":\"2025-10-02T15:44:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\"},\"description\":\"Os tripulantes da Esta\u00e7\u00e3o Salva-vidas de Viana do Castelo auxiliaram esta quarta-feira tr\u00eas pessoas que seguiam a bordo de um veleiro com bandeira brit\u00e2nica, que sofreu danos no leme ap\u00f3s uma intera\u00e7\u00e3o com orcas, a cerca de nove milhas n\u00e1uticas (16,7 quil\u00f3metros) a sudoeste da barra de Viana do Castelo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/estacao-salva-vidas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/estacao-salva-vidas.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/2025\\\/10\\\/02\\\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orcas provocam danos em veleiro brit\u00e2nico ao largo de Viana do Castelo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/\",\"name\":\"Altominho.tv\",\"description\":\"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/#\\\/schema\\\/person\\\/4e536851627d7914baf3dac752b6af22\",\"name\":\"Altominho.tv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Logo_Avatar_2-150x150.jpg\",\"caption\":\"Altominho.tv\"},\"url\":\"https:\\\/\\\/www.altominho.tv\\\/site\\\/author\\\/altominhotv-tecnico\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Orcas provocam danos em veleiro brit\u00e2nico ao largo de Viana do Castelo","description":"Os tripulantes da Esta\u00e7\u00e3o Salva-vidas de Viana do Castelo auxiliaram esta quarta-feira tr\u00eas pessoas que seguiam a bordo de um veleiro com bandeira brit\u00e2nica, que sofreu danos no leme ap\u00f3s uma intera\u00e7\u00e3o com orcas, a cerca de nove milhas n\u00e1uticas (16,7 quil\u00f3metros) a sudoeste da barra de Viana do Castelo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/","og_locale":"pt_PT","og_type":"article","og_title":"Orcas provocam danos em veleiro brit\u00e2nico ao largo de Viana do Castelo","og_description":"Os tripulantes da Esta\u00e7\u00e3o Salva-vidas de Viana do Castelo auxiliaram esta quarta-feira tr\u00eas pessoas que seguiam a bordo de um veleiro com bandeira brit\u00e2nica, que sofreu danos no leme ap\u00f3s uma intera\u00e7\u00e3o com orcas, a cerca de nove milhas n\u00e1uticas (16,7 quil\u00f3metros) a sudoeste da barra de Viana do Castelo.","og_url":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/","og_site_name":"Altominho.tv","article_publisher":"https:\/\/www.facebook.com\/altominhotv","article_published_time":"2025-10-02T15:43:57+00:00","article_modified_time":"2025-10-02T15:44:03+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/estacao-salva-vidas.jpg","type":"image\/jpeg"}],"author":"Altominho.tv","twitter_card":"summary_large_image","twitter_creator":"@altominhoTV","twitter_site":"@altominhoTV","twitter_misc":{"Escrito por":"Altominho.tv","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/#article","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/"},"author":{"name":"Altominho.tv","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22"},"headline":"Orcas provocam danos em veleiro brit\u00e2nico ao largo de Viana do Castelo","datePublished":"2025-10-02T15:43:57+00:00","dateModified":"2025-10-02T15:44:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/"},"wordCount":178,"image":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/estacao-salva-vidas.jpg","keywords":["Sociedade"],"articleSection":["Viana do Castelo"],"inLanguage":"pt-PT","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.altominho.tv\/site\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/","url":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/","name":"Orcas provocam danos em veleiro brit\u00e2nico ao largo de Viana do Castelo","isPartOf":{"@id":"https:\/\/www.altominho.tv\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/#primaryimage"},"image":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/estacao-salva-vidas.jpg","datePublished":"2025-10-02T15:43:57+00:00","dateModified":"2025-10-02T15:44:03+00:00","author":{"@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22"},"description":"Os tripulantes da Esta\u00e7\u00e3o Salva-vidas de Viana do Castelo auxiliaram esta quarta-feira tr\u00eas pessoas que seguiam a bordo de um veleiro com bandeira brit\u00e2nica, que sofreu danos no leme ap\u00f3s uma intera\u00e7\u00e3o com orcas, a cerca de nove milhas n\u00e1uticas (16,7 quil\u00f3metros) a sudoeste da barra de Viana do Castelo.","breadcrumb":{"@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/#primaryimage","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/estacao-salva-vidas.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2025\/10\/estacao-salva-vidas.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.altominho.tv\/site\/2025\/10\/02\/orcas-provocam-danos-em-veleiro-britanico-ao-largo-de-viana-do-castelo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.altominho.tv\/site\/"},{"@type":"ListItem","position":2,"name":"Orcas provocam danos em veleiro brit\u00e2nico ao largo de Viana do Castelo"}]},{"@type":"WebSite","@id":"https:\/\/www.altominho.tv\/site\/#website","url":"https:\/\/www.altominho.tv\/site\/","name":"Altominho.tv","description":"A sua regi\u00e3o \u00e0 dist\u00e2ncia de um clique...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.altominho.tv\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.altominho.tv\/site\/#\/schema\/person\/4e536851627d7914baf3dac752b6af22","name":"Altominho.tv","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","url":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","contentUrl":"https:\/\/www.altominho.tv\/site\/wp-content\/uploads\/2019\/11\/Logo_Avatar_2-150x150.jpg","caption":"Altominho.tv"},"url":"https:\/\/www.altominho.tv\/site\/author\/altominhotv-tecnico\/"}]}},"_links":{"self":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/123577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/comments?post=123577"}],"version-history":[{"count":1,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/123577\/revisions"}],"predecessor-version":[{"id":123579,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/posts\/123577\/revisions\/123579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media\/123578"}],"wp:attachment":[{"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/media?parent=123577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/categories?post=123577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.altominho.tv\/site\/wp-json\/wp\/v2\/tags?post=123577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}